{"id":1058,"date":"2016-10-19T09:36:57","date_gmt":"2016-10-19T07:36:57","guid":{"rendered":"http:\/\/asv-botnang.de\/volleyball\/?p=1058"},"modified":"2016-10-19T09:36:57","modified_gmt":"2016-10-19T07:36:57","slug":"sieg-und-niederlage-am-ersten-heimspieltag-fuer-die-herren-2-des-asv-botnang","status":"publish","type":"post","link":"https:\/\/asv-botnang.de\/volleyball\/sieg-und-niederlage-am-ersten-heimspieltag-fuer-die-herren-2-des-asv-botnang\/","title":{"rendered":"Sieg und Niederlage am ersten Heimspieltag f\u00fcr die Herren 2 des ASV Botnang"},"content":{"rendered":"<p>Die Landesliga-Herren des ASV Botnang konnten am ersten Heimspieltag die ersten Punkte einfahren.<!--more--> Die Herren 2 gewann gegen die zweite Mannschaft des MTV Ludwigsburg mit 3:0. Das zweite Spiel verloren die Gastgeber gegen den TV Hausen mit 0:3.<\/p>\n<p><strong>ASV Botnang 2 &#8211; MTV Ludwigsburg 2\t\t3:0 (25:22, 25:22, 25:17)<\/strong><br \/>\nNach der Niederlage am ersten Spieltag wurde im Training hart gearbeitet und die M\u00e4nner von Trainer Alexander Neu starteten konzentriert gegen den Oberliga-Absteiger. Der erste Satz war lange ausgeglichen, jedoch zog der Gast am Ende den k\u00fcrzeren und die Botnanger feierten den ersten Satzgewinn in der neuen Saison. Auch im zweiten Satz entwickelte sich ein enges Spiel. Durch druckvolle Aufschl\u00e4ge sowie gute Block-Abwehr-Aktionen konnte sich die Mannschaft um Kapit\u00e4n Dominik Seifert absetzen und brachte den Vorsprung in Ziel. Gerrit Feifel und Dirk Stadelhofer spielten im Angriff nahezu fehlerlos und dr\u00fcckten im dritten Satz dem Spiel ihren Stempel auf. Die Luft bei den G\u00e4sten aus Ludwigsburg war raus und die Botnanger holten \u00fcber die Zwischenst\u00e4nde 8:2 und 20:13 den ersten Saisonsieg nach Hause. <\/p>\n<p><strong>ASV Botnang 2 &#8211; TV Hausen\t0:3 (18:25, 9:25, 22:25)<\/strong><br \/>\nIm zweiten Spiel des Tages war der TV Hausen zu Gast in Botnang. Leider lief bei den Botnanger im Gegensatz zum ersten Spiel nicht viel zusammen und Libero Stefan Blanke wurde schmerzlich vermisst. Die Botnanger erwischten einen schlechten Start ins Spiel. Die eigenen Aufschl\u00e4ge waren wenig druckvoll und die Schw\u00e4chen in der Annahme gestalteten den eigenen Spielaufbau schwierig. Durch eine effektive Chancenverwertung und eine gut organisierte Block- und Abwehrreihe gewannen die G\u00e4ste die ersten beiden S\u00e4tze deutlich. In Satz drei fanden die Botnanger dann besser in Spiel und konnten sich lange Zeit auf Augenh\u00f6he mit den G\u00e4sten aus Hausen pr\u00e4sentieren. Am Ende war die eigene Fehlerquote jedoch zu hoch und Hausen gewann das Spiel. <\/p>\n<p>Das Team muss nun im Training weiter Gas geben und konzentriert arbeiten, um in den kommenden Spielen eine konstantere Leistung abrufen zu k\u00f6nnen. <\/p>\n<p>Schon am kommenden Mittwoch geht es im Pokal gegen Ligakonkurrenten MTV Ludwigsburg 3 weiter. Anpfiff ist um 21:00 Uhr in der BSH Botnang. Das n\u00e4chste Spiel in der Landesliga findet am 29.10.2016 statt. Auch hier hei\u00dft der Gegner MTV Ludwigsburg 3. <\/p>\n<p>F\u00fcr den ASV spielten: Stefan Blanke, Gerrit Feifel, Manuel Haas, Nils Kaiser, Lennart Pfaller, Stefan Schnupp, Vincent Schubert, Dominik Seifert, Bernd Seybold, Dirk Stadelhofer, Frieder Steinacker, Mark Szameitat<br \/>\nTrainer: Alexander Neu<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Landesliga-Herren des ASV Botnang konnten am ersten Heimspieltag die ersten Punkte einfahren.<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/posts\/1058"}],"collection":[{"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/comments?post=1058"}],"version-history":[{"count":1,"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/posts\/1058\/revisions"}],"predecessor-version":[{"id":1059,"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/posts\/1058\/revisions\/1059"}],"wp:attachment":[{"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/categories?post=1058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asv-botnang.de\/volleyball\/wp-json\/wp\/v2\/tags?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}